{"id":8774,"date":"2020-03-08T03:02:48","date_gmt":"2020-03-08T03:02:48","guid":{"rendered":"http:\/\/timeline-germany.de\/wp-content\/uploads\/2020\/03\/ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder.jpg"},"modified":"2020-03-08T03:02:48","modified_gmt":"2020-03-08T03:02:48","slug":"ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder-2","status":"inherit","type":"attachment","link":"https:\/\/timeline-germany.de\/tr\/ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder-2","title":{"rendered":"ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder"},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout"},"class_list":["post-8774","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/timeline-germany.de\/wp-content\/uploads\/2020\/03\/ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/timeline-germany.de\/wp-content\/uploads\/2020\/03\/ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/timeline-germany.de\/wp-content\/uploads\/2020\/03\/ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder-300x169.jpg 300w, https:\/\/timeline-germany.de\/wp-content\/uploads\/2020\/03\/ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder.jpg 720w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":720,"height":406,"file":"2020\/03\/ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder.jpg","sizes":{"thumbnail":{"file":"ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/timeline-germany.de\/wp-content\/uploads\/2020\/03\/ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder-150x150.jpg"},"medium":{"file":"ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder-300x169.jpg","width":300,"height":169,"mime_type":"image\/jpeg","source_url":"https:\/\/timeline-germany.de\/wp-content\/uploads\/2020\/03\/ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder-300x169.jpg"},"colormag-highlighted-post":{"file":"ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder-392x272.jpg","width":392,"height":272,"mime_type":"image\/jpeg","source_url":"https:\/\/timeline-germany.de\/wp-content\/uploads\/2020\/03\/ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder-392x272.jpg"},"colormag-featured-post-medium":{"file":"ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder-390x205.jpg","width":390,"height":205,"mime_type":"image\/jpeg","source_url":"https:\/\/timeline-germany.de\/wp-content\/uploads\/2020\/03\/ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder-390x205.jpg"},"colormag-featured-post-small":{"file":"ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder-130x90.jpg","width":130,"height":90,"mime_type":"image\/jpeg","source_url":"https:\/\/timeline-germany.de\/wp-content\/uploads\/2020\/03\/ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder-130x90.jpg"},"full":{"file":"ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder.jpg","width":720,"height":406,"mime_type":"image\/jpeg","source_url":"https:\/\/timeline-germany.de\/wp-content\/uploads\/2020\/03\/ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/timeline-germany.de\/wp-content\/uploads\/2020\/03\/ueberfuellte-griechische-lager-spd-chef-fordert-hilfe-fuer-gefluechtete-kinder.jpg","_links":{"self":[{"href":"https:\/\/timeline-germany.de\/tr\/wp-json\/wp\/v2\/media\/8774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/timeline-germany.de\/tr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/timeline-germany.de\/tr\/wp-json\/wp\/v2\/types\/attachment"}],"replies":[{"embeddable":true,"href":"https:\/\/timeline-germany.de\/tr\/wp-json\/wp\/v2\/comments?post=8774"}]}}